{"id":27195,"date":"2026-06-04T22:31:11","date_gmt":"2026-06-04T20:31:11","guid":{"rendered":"https:\/\/leblogaroger.eu\/?p=27195"},"modified":"2026-06-04T22:31:12","modified_gmt":"2026-06-04T20:31:12","slug":"cognac-grande-champagne-famille-duluc-lot-70","status":"publish","type":"post","link":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/","title":{"rendered":"Cognac Grande Champagne Famille DULUC Lot 70"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">\u00c0 la r\u00e9daction du Blog \u00e0 Roger, on a une certaine affection pour les s\u00e9lections d&rsquo;<strong><a href=\"https:\/\/www.authentic-spirits.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Authentic Spirits<\/a><\/strong>, et entres autres pour ce qu&rsquo;ils proposent avec le domaine <strong>Duluc<\/strong>. Jusqu&rsquo;\u00e0 pr\u00e9sent, le sans-faute n&rsquo;est pas loin d&rsquo;\u00eatre atteint. Entre un remarquable <a href=\"https:\/\/leblogaroger.eu\/index.php\/2025\/12\/21\/some-kind-ov-authentic-amateur-spirits\/\" target=\"_blank\" rel=\"noreferrer noopener\">1984<\/a> s\u00e9lectionn\u00e9 entre amateurs, un lot <a href=\"https:\/\/leblogaroger.eu\/index.php\/2024\/10\/15\/some-kind-ov-grande-champagne\/\" target=\"_blank\" rel=\"noreferrer noopener\">1987<\/a> qui nous a particuli\u00e8rement s\u00e9duits <em>(avec une mention sp\u00e9ciale pour Roger, du service imprimerie, qui en parle encore \u00e0 la pause caf\u00e9)<\/em>, et un <a href=\"https:\/\/leblogaroger.eu\/index.php\/2026\/05\/29\/cognac-grande-champagne-guillaume-duluc-napoleon-full-proof\/\" target=\"_blank\" rel=\"noreferrer noopener\">Napol\u00e9on<\/a> assez d\u00e9coiffant mais qualitatif, toutes les r\u00e9f\u00e9rences pass\u00e9es sur notre banc d&rsquo;essai en sont ressorties avec les honneurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autant dire que nous abordions cette nouvelle d\u00e9gustation avec une certaine confiance, surtout en voyant que notre ami Aur\u00e9lien le consid\u00e8re comme une de ses plus belles sorties&#8230; Bref, ouvrir le sample aura \u00e9t\u00e9 un chouette moment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concernant la famille Duluc, voici les informations que j&rsquo;ai pu glaner ci et l\u00e0:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Chez Duluc, le cognac n&rsquo;est pas seulement une affaire de terroir ou de savoir-faire. C&rsquo;est avant tout une histoire de famille qui se transmet depuis plus d&rsquo;un si\u00e8cle au c\u0153ur de la Grande Champagne.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L&rsquo;aventure d\u00e9bute apr\u00e8s la crise du phyllox\u00e9ra, lorsque la famille Duluc acquiert, en 1884, une propri\u00e9t\u00e9 \u00e0 Touzac. Sur ces terres argilo-calcaires particuli\u00e8rement r\u00e9put\u00e9es, plusieurs g\u00e9n\u00e9rations se succ\u00e8dent avant que Pierre et Daniel ne reprennent le domaine en 1978. Aujourd&rsquo;hui, Guillaume poursuit cette aventure familiale avec la m\u00eame philosophie : produire de grands cognacs sans jamais oublier que derri\u00e8re chaque f\u00fbt se cachent des femmes, des hommes et des souvenirs.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Cette approche se ressent imm\u00e9diatement lorsqu&rsquo;on \u00e9change avec lui. L\u00e0 o\u00f9 certains cultivent une image solennelle du cognac, Guillaume pr\u00e9f\u00e8re parler de passion, de partage et de convivialit\u00e9. Les collaborations avec les embouteilleurs ind\u00e9pendants lui permettent de travailler avec des passionn\u00e9s, d&rsquo;\u00e9changer des id\u00e9es, des bouteilles, et parfois m\u00eame de prolonger la discussion autour d&rsquo;un repas au cognac et d&rsquo;un brasero, comme entre vieux amis.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les cognacs Duluc sont ainsi \u00e0 l&rsquo;image de leur propri\u00e9taire : profond\u00e9ment enracin\u00e9s dans la tradition, mais jamais fig\u00e9s. <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Qu&rsquo;il s&rsquo;agisse d&rsquo;un jeune cognac atteignant 70% d&rsquo;alcool ou cette vieille eau-de-vie distill\u00e9e par son oncle Claude en 1970 dans un alambic de 10hl que Guillaume utilise toujours.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Une vision sinc\u00e8re, humaine et passionn\u00e9e qui rappelle qu&rsquo;un grand cognac peut \u00eatre \u00e0 la fois tr\u00e8s s\u00e9rieux\u2026 et terriblement vivant.<\/em><\/p>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:261px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1195\" height=\"896\" class=\"wp-block-cover__image-background wp-image-27198 size-full\" alt=\"\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo.png\" style=\"object-position:44% 70%\" data-object-fit=\"cover\" data-object-position=\"44% 70%\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo.png 1195w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo-595x446.png 595w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo-767x575.png 767w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo-960x720.png 960w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_dwjowfdwjowfdwjo-800x600.png 800w\" sizes=\"auto, (max-width: 1195px) 100vw, 1195px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#5b4c3a\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nez<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Enorme gourmandise fruit\u00e9e qui ferait penser \u00e0 des sirops ou jus de p\u00eaches, abricots, raisin secs, figues avec pas mal de fleurs s\u00e8ches, de vanille accompagn\u00e9e d&rsquo;\u00e9pice et d&rsquo;une fine r\u00e9glisse, pour ensuite offir un c\u00f4t\u00e9 plus tropical et luxuriant avec de la mangue sech\u00e9es et de la banane bien m\u00fbre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vraiment captivant et qui n&rsquo;appelle qu&rsquo;\u00e0 une chose, d\u00e9guster car \u00e7a donne vraiment une envie folle d&rsquo;y tremper les l\u00e8vres&#8230;bon sang, on a toujours dit que tout le plaisir est l&rsquo;attente, ben pas ici, j&rsquo;y vais ! \ud83d\ude42<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bouche<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s belle gourmandise sur les fruits confits encore une fois avec les agrumes, les figues, les dattes, les raisins secs gorg\u00e9s de soleil, les \u00e9pices fines sur une impression hyper huileuse et grasse&#8230;bon sang, quelle mati\u00e8re l\u00e0 dedans, un vrai concentr\u00e9 de <em>(toute)<\/em> Grande Champagne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bois\u00e9, hyper classe, est bien entendu pr\u00e9sent et tr\u00e8s p\u00e2tin\u00e9, \u00e9l\u00e9gant et nous offre des fleurs sech\u00e9es, un l\u00e9ger tabac, un bois laqu\u00e9 hyper fin et quelques douces \u00e9pices&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les fruits \u00e0 coque termine ce magnifique bouquet de saveurs sur une belle longueur toute douce&#8230; <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">248\u20ac<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un beau moment suspendu dans le temps, vraiment une toute grande s\u00e9lection ! Bravo !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Score<\/h2>\n\n\n\n<div class=\"rating-badge\" data-score=\"93\">\n  <span class=\"rb-num\"><\/span>\n  <div class=\"rb-right\">\n    <span class=\"rb-label\"><\/span>\n    <span class=\"rb-desc\"><\/span>\n  <\/div>\n<\/div>\n\n<style>\n  .rating-badge { font-family: sans-serif; display: inline-flex; align-items: center; gap: 10px; margin: 0.5rem 0; }\n  .rating-badge .rb-num { font-size: 40px; font-weight: 600; line-height: 1; }\n  .rating-badge .rb-right { display: flex; flex-direction: column; gap: 4px; }\n  .rating-badge .rb-label { display: inline-block; padding: 3px 12px; border-radius: 6px; font-size: 13px; font-weight: 500; }\n  .rating-badge .rb-desc { font-size: 13px; color: #666; }\n<\/style>\n\n<script>\n  document.querySelectorAll('.rating-badge').forEach(function(el) {\n    var score = parseInt(el.getAttribute('data-score'), 10);\n    var zones = {\n      100: { label: \"Mythique\",      color: \"#26215C\", bg: \"#EEEDFE\", desc: \"On ne le boit pas tout de suite. On le contemple. On reviendra demain.\" },\n       99: { label: \"L\u00e9gendaire\",    color: \"#3C3489\", bg: \"#EEEDFE\", desc: \"On garde la bouteille vide. Sur l'\u00e9tag\u00e8re. Encadr\u00e9e.\" },\n       98: { label: \"Transcendant\",  color: \"#534AB7\", bg: \"#EEEDFE\", desc: \"On pleure un peu. C'est normal.\" },\n       97: { label: \"Exceptionnel\",  color: \"#185FA5\", bg: \"#E6F1FB\", desc: \"On appelle son meilleur pote pour lui raconter.\" },\n       96: { label: \"Envo\u00fbtant\",     color: \"#185FA5\", bg: \"#E6F1FB\", desc: \"On annule ses vacances pour rester pr\u00e8s de la cave.\" },\n       95: { label: \"Saisissant\",    color: \"#185FA5\", bg: \"#E6F1FB\", desc: \"On relit l'\u00e9tiquette trois fois pour \u00eatre s\u00fbr d'avoir bien lu.\" },\n       94: { label: \"\u00c9blouissant\",   color: \"#0C447C\", bg: \"#E6F1FB\", desc: \"On prend une photo du verre. Oui, du verre.\" },\n       93: { label: \"Fascinant\",     color: \"#0F6E56\", bg: \"#E1F5EE\", desc: \"On retourne chez le caviste le jour m\u00eame.\" },\n       92: { label: \"Impressionnant\",color: \"#0F6E56\", bg: \"#E1F5EE\", desc: \"On t\u00e9l\u00e9phone au mec qui a fait \u00e7a pour le f\u00e9liciter. Il est surpris. On l'est aussi.\" },\n       91: { label: \"Remarquable\",   color: \"#0F6E56\", bg: \"#E1F5EE\", desc: \"On cache la bouteille pour ne pas la partager.\" },\n       90: { label: \"Excellent\",     color: \"#3B6D11\", bg: \"#EAF3DE\", desc: \"On en parle encore le lendemain au bureau, m\u00eame \u00e0 ceux qui s'en foutent.\" },\n       89: { label: \"S\u00e9duisant\",     color: \"#3B6D11\", bg: \"#EAF3DE\", desc: \"On annule ses projets pour finir la bouteille tranquillement.\" },\n       88: { label: \"G\u00e9n\u00e9reux\",      color: \"#3B6D11\", bg: \"#EAF3DE\", desc: \"On commence \u00e0 regretter de ne pas en avoir pris deux bouteilles. \" },\n       87: { label: \"Solide\",        color: \"#639922\", bg: \"#EAF3DE\", desc: \"On l'ouvre un mardi soir, juste parce que. \" },\n       86: { label: \"Agr\u00e9able\",      color: \"#639922\", bg: \"#EAF3DE\", desc: \"On le sort quand les invit\u00e9s m\u00e9ritent mieux que la piquette habituelle. \" },\n       85: { label: \"Plaisant\",      color: \"#854F0B\", bg: \"#FAEEDA\", desc: \"On se ressert sans se poser de questions.\" },\n    };\n\n    var below = [\n      { min: 75, label: \"Bof bof\",  color: \"#854F0B\", bg: \"#FAEEDA\", desc: \"disons que ce n\u2019est pas forc\u00e9ment une bouteille que je me pr\u00e9cipiterais \u00e0 recommander, pour tout un tas de raisons \ud83d\ude42 \" },\n      { min: 70, label: \"Oubliez\",  color: \"#993C1D\", bg: \"#FAECE7\", desc: \"Dans la moyenne basse \u2014 oubliez cette chose.\" },\n      { min: 0,  label: \"\u00c9vitez\",   color: \"#A32D2D\", bg: \"#FCEBEB\", desc: \"Pwaaaa, c'est vraiment pas tr\u00e8s bon ce truc\u2026\" },\n    ];\n\n    var z;\n    if (score >= 85) {\n      z = zones[score] || zones[85];\n    } else {\n      z = below.find(function(b) { return score >= b.min; });\n    }\n\n    el.querySelector('.rb-num').textContent = score;\n    el.querySelector('.rb-num').style.color = z.color;\n    el.querySelector('.rb-label').textContent = z.label;\n    el.querySelector('.rb-label').style.background = z.bg;\n    el.querySelector('.rb-label').style.color = z.color;\n    el.querySelector('.rb-desc').textContent = z.desc;\n  });\n<\/script>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">N&rsquo;h\u00e9sitez pas \u00e0 vous abonner \u00e0 la newsletter pour recevoir toutes les prochaines publications dans votre bo\u00eete mail \ud83d\ude09<\/p>\n\n\n\n<div style=\"text-align: center;\"><iframe src=\"https:\/\/leblogaroger.substack.com\/embed\" style=\"solid #EEE; background: white\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/di>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 la r\u00e9daction du Blog \u00e0 Roger, on a une certaine affection pour les s\u00e9lections d&rsquo;Authentic Spirits, et entres autres pour ce qu&rsquo;ils proposent avec le domaine Duluc. Jusqu&rsquo;\u00e0 pr\u00e9sent, le sans-faute n&rsquo;est pas loin d&rsquo;\u00eatre atteint. Entre un remarquable 1984 s\u00e9lectionn\u00e9 entre amateurs, un lot 1987 qui nous a <a href=\"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/\" class=\"btn btn-link continue-link\">Voir plus&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":27199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-27195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cognac"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cognac Grande Champagne Famille DULUC Lot 70 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cognac Grande Champagne Famille DULUC Lot 70 -\" \/>\n<meta property=\"og:description\" content=\"\u00c0 la r\u00e9daction du Blog \u00e0 Roger, on a une certaine affection pour les s\u00e9lections d&rsquo;Authentic Spirits, et entres autres pour ce qu&rsquo;ils proposent avec le domaine Duluc. Jusqu&rsquo;\u00e0 pr\u00e9sent, le sans-faute n&rsquo;est pas loin d&rsquo;\u00eatre atteint. Entre un remarquable 1984 s\u00e9lectionn\u00e9 entre amateurs, un lot 1987 qui nous a Voir plus...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leblogaroger\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/leblogaroger\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-04T20:31:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T20:31:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/\"},\"author\":{\"name\":\"Roger\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"headline\":\"Cognac Grande Champagne Famille DULUC Lot 70\",\"datePublished\":\"2026-06-04T20:31:11+00:00\",\"dateModified\":\"2026-06-04T20:31:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/\"},\"wordCount\":678,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/duluc70.png\",\"articleSection\":[\"cognac\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/\",\"name\":\"Cognac Grande Champagne Famille DULUC Lot 70 -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/duluc70.png\",\"datePublished\":\"2026-06-04T20:31:11+00:00\",\"dateModified\":\"2026-06-04T20:31:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/duluc70.png\",\"contentUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/duluc70.png\",\"width\":1020,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2026\\\/06\\\/04\\\/cognac-grande-champagne-famille-duluc-lot-70\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leblogaroger.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cognac Grande Champagne Famille DULUC Lot 70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/\",\"name\":\"\",\"description\":\"Mundi placet et spiritus minima...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leblogaroger.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\",\"name\":\"Roger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"caption\":\"Roger\"},\"sameAs\":[\"http:\\\/\\\/www.leblogaroger.eu\",\"https:\\\/\\\/www.facebook.com\\\/leblogaroger\",\"https:\\\/\\\/www.instagram.com\\\/rogercaroni\\\/\"],\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/author\\\/admin5027\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cognac Grande Champagne Famille DULUC Lot 70 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/","og_locale":"fr_FR","og_type":"article","og_title":"Cognac Grande Champagne Famille DULUC Lot 70 -","og_description":"\u00c0 la r\u00e9daction du Blog \u00e0 Roger, on a une certaine affection pour les s\u00e9lections d&rsquo;Authentic Spirits, et entres autres pour ce qu&rsquo;ils proposent avec le domaine Duluc. Jusqu&rsquo;\u00e0 pr\u00e9sent, le sans-faute n&rsquo;est pas loin d&rsquo;\u00eatre atteint. Entre un remarquable 1984 s\u00e9lectionn\u00e9 entre amateurs, un lot 1987 qui nous a Voir plus...","og_url":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/","article_publisher":"https:\/\/www.facebook.com\/leblogaroger\/","article_author":"https:\/\/www.facebook.com\/leblogaroger","article_published_time":"2026-06-04T20:31:11+00:00","article_modified_time":"2026-06-04T20:31:12+00:00","og_image":[{"width":1020,"height":600,"url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png","type":"image\/png"}],"author":"Roger","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Roger","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#article","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/"},"author":{"name":"Roger","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"headline":"Cognac Grande Champagne Famille DULUC Lot 70","datePublished":"2026-06-04T20:31:11+00:00","dateModified":"2026-06-04T20:31:12+00:00","mainEntityOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/"},"wordCount":678,"commentCount":0,"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png","articleSection":["cognac"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/","url":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/","name":"Cognac Grande Champagne Famille DULUC Lot 70 -","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#primaryimage"},"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png","datePublished":"2026-06-04T20:31:11+00:00","dateModified":"2026-06-04T20:31:12+00:00","author":{"@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"breadcrumb":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#primaryimage","url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png","contentUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2026\/05\/duluc70.png","width":1020,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/leblogaroger.eu\/index.php\/2026\/06\/04\/cognac-grande-champagne-famille-duluc-lot-70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leblogaroger.eu\/"},{"@type":"ListItem","position":2,"name":"Cognac Grande Champagne Famille DULUC Lot 70"}]},{"@type":"WebSite","@id":"https:\/\/leblogaroger.eu\/#website","url":"https:\/\/leblogaroger.eu\/","name":"","description":"Mundi placet et spiritus minima...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leblogaroger.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a","name":"Roger","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","caption":"Roger"},"sameAs":["http:\/\/www.leblogaroger.eu","https:\/\/www.facebook.com\/leblogaroger","https:\/\/www.instagram.com\/rogercaroni\/"],"url":"https:\/\/leblogaroger.eu\/index.php\/author\/admin5027\/"}]}},"_links":{"self":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/27195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/comments?post=27195"}],"version-history":[{"count":15,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/27195\/revisions"}],"predecessor-version":[{"id":27216,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/27195\/revisions\/27216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media\/27199"}],"wp:attachment":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media?parent=27195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/categories?post=27195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/tags?post=27195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}