{"id":22928,"date":"2025-02-09T15:37:21","date_gmt":"2025-02-09T14:37:21","guid":{"rendered":"https:\/\/leblogaroger.eu\/?p=22928"},"modified":"2025-02-10T18:25:31","modified_gmt":"2025-02-10T17:25:31","slug":"some-kind-ov-wu-dram-clan","status":"publish","type":"post","link":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/","title":{"rendered":"Some Kind Ov Wu Dram Clan"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Revoici les copains du <strong>Wu Dram Clan<\/strong> avec quelques nouveaut\u00e9s que je vous propose de d\u00e9couvrir rapidement. Au programme, deux rhums et un rye whiskey mis en bouteilles pour nos trois \u00e9picuriens d&rsquo;outre-Rhin. Et le moins que l&rsquo;on puisse dire est qu&rsquo;ils ne prennent pas trop le temps de se reposer, entre leurs diff\u00e9rentes s\u00e9lections, leurs activit\u00e9s professionnelles et leurs voyages&#8230;. bravo pour la constance !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous commencerons par un rhum dans lequel pas mal d&rsquo;espoirs seront plac\u00e9s, un Trinidad du mill\u00e9sime 2003&#8230; et \u00e7a, ici on les trouve souvent tr\u00e8s bons, donc on esp\u00e8re que cette version sera dans la m\u00eame veine !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensuite, un passage \u00e0 Saint Lucia pour un Chairman Reserve du mill\u00e9sime 2009 \u00e2g\u00e9 de 14 ans sur place, 100% vendome pot still.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, retour dans le pays qui part le plus en couilles en 2025, les USA et leur clown\/pr\u00e9sident avec un Rye Whiskey de chez Willet \u00e2g\u00e9 de 7 ans.<\/p>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:290px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" class=\"wp-block-cover__image-background wp-image-22930 size-large\" alt=\"\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-960x960.png\" data-object-fit=\"cover\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-960x960.png 960w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-595x595.png 595w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-768x768.png 768w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-1536x1536.png 1536w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505-720x720.png 720w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250208_130505.png 2048w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#954536\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-white-color has-text-color has-background has-link-color has-large-font-size wp-elements-8e74265ebe85ca7878c0c1301e01bf7c wp-block-paragraph\" style=\"background-color:#0000004a\">TDL &#8211; 2003\/2025 &#8211; 55.2%<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trinidad Distillery Limited<\/strong>, un endroit qu&rsquo;on aime assez bien ici avec de tr\u00e8s belles surprises en terme de rhums lourds, flirtant de temps en temps avec les anciens voisins de chez Caroni. Ici, mill\u00e9sime 2003 \u00e2g\u00e9 de <strong>22 ans<\/strong>, dont 13 sur place, et mis en bouteille \u00e0 <strong>55.2%<\/strong> d&rsquo;alcool.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nez<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le profil semble plus l\u00e9ger que les diff\u00e9rents 2003 d\u00e9j\u00e0 d\u00e9gust\u00e9s, on va plus y retrouver de la cr\u00e8me flamb\u00e9e, de la vanille, des fruits rouges comme le cassis, les mures englob\u00e9s d&rsquo;un fin voile menthol\u00e9, de caramel, d&rsquo;\u00e9pices l\u00e9g\u00e8res.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;ensemble semble moins lourd, plus \u00e9l\u00e9gant et fin ce qui n&rsquo;est au finale rien de n\u00e9gatif, juste l\u00e9g\u00e8rement diff\u00e9rents de ce \u00e0 quoi je m&rsquo;attendais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bouche<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;entr\u00e9e en bouche est relativement douce et cr\u00e9meuse avec encore cette cr\u00e8me br\u00fbl\u00e9e accompagn\u00e9e de grains de cassis, de caramel, de vanille, du fuddge, des \u00e9pices et des notes l\u00e9g\u00e8rement torr\u00e9fi\u00e9es et chocolat\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bois\u00e9e est bien entendu pr\u00e9sent aussi apr\u00e8s 22 ans, nous allons y d\u00e9couvrir du tabac, r\u00e9glisse, chocolat au lait caram\u00e9lis\u00e9, sur des mangues sech\u00e9es et l\u00e9g\u00e8rement poivr\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les 55% sont un exemple d&rsquo;int\u00e9gration, c&rsquo;est vraiment quelque chose de tr\u00e8s agr\u00e9able et plaisant, tant le c\u00f4t\u00e9 cr\u00e9meux et l\u00e9g\u00e8rement caram\u00e9lis\u00e9 englobe le palais. C&rsquo;est bonbon cette petite crasse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">199\u20ac<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce rhum est clairement dangeureux, il passe tout seul et est tr\u00e8s agr\u00e9able. On semble se retrouver sur un mix des meilleurs \u00e9l\u00e9ments des rhums light de chez TDL avec une pointe des typicit\u00e9s des rhums lourd de l&rsquo;\u00eele. C&rsquo;est plein de gourmandise et d&rsquo;exotisme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Score<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">90\/100<\/p>\n\n\n\n<div class=\"wp-block-cover is-light\" style=\"min-height:290px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" class=\"wp-block-cover__image-background wp-image-22931 size-large\" alt=\"\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-960x960.png\" data-object-fit=\"cover\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-960x960.png 960w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-595x595.png 595w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-768x768.png 768w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-1536x1536.png 1536w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332-720x720.png 720w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141332.png 2048w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#7d8488\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-white-color has-text-color has-background has-link-color has-large-font-size wp-elements-1d6c5cbee72c4ead3d36694367a40534 wp-block-paragraph\" style=\"background-color:#0000004a\">Chairman Reserve &#8211; 2009\/2025 &#8211; 58.3%<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Distill\u00e9 en <strong>2009 <\/strong>\u00e0 partir de l&rsquo;alambic Vend\u00f4me de chez St Lucia Distillers, ce rhum de 14 ans d&rsquo;\u00e2ge est rest\u00e9 enferm\u00e9 dans son ex f\u00fbt de Jack Daniels sur l&rsquo;\u00eele jusqu&rsquo;\u00e0 se mise en bouteille pour WDC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nez<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un nez tr\u00e8s frais, avec des traces de solvants, de caramel, de vernis, des fruits exotiques bien murs, d&rsquo;herbes aromatiques, de bois\u00e9 et d&rsquo;agrumes l\u00e9g\u00e8rement acides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec le temps, un c\u00f4t\u00e9 plus \u00ab\u00a0garage\u00a0\u00bb va faire son apparition avec quelques traces d&rsquo;huiles, de t\u00e9r\u00e9bantine, toujours mix\u00e9 avec les fruits tropicaux comme la mangue ou la banane mure et des \u00e9pices caram\u00e9lis\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le chocolat est bien l\u00e0, avec du tabac, de la r\u00e9glisse et une pointe d&rsquo;ancho\u00efade et d&rsquo;olives noires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bouche<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Entr\u00e9e en bouche relativement douce et parfum\u00e9e, l&rsquo;olive verte est directement l\u00e0 accompagn\u00e9e de fruits tropicaux l\u00e9g\u00e8rement plus acides, napp\u00e9s de caramel et de fruits \u00e0 coque torr\u00e9fi\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les fruits rouges font ensuite leur entr\u00e9e pour accompagner cet ensemble tr\u00e8s complexe o\u00f9 l&rsquo;on naviguerait entre un rhum Jama\u00efquain et un de ses homologues de Barbade ou Sainte Lucie<em><sup> (forc\u00e9ment)<\/sup><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La finale, l\u00e9g\u00e8rement fum\u00e9e pourrait encore nous faire croire \u00e0 un profil rappellant Hampden ou autre Long Pond.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">129\u20ac<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Etonnant, je pense que c&rsquo;est le premier Sainte Lucie que je d\u00e9couvre avec ce profil&#8230; On s&rsquo;\u00e9loigne assez bien du profil hyper chaleureux des rhum de l&rsquo;\u00eele pour retrouver quelque chose de plus marqu\u00e9 par les olives et poiscaille&#8230; Serait ce un Chairman High Esters ? \ud83d\ude42<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Score<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">88\/100<\/p>\n\n\n\n<div class=\"wp-block-cover\" style=\"min-height:290px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" class=\"wp-block-cover__image-background wp-image-22932 size-large\" alt=\"\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-960x960.png\" data-object-fit=\"cover\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-960x960.png 960w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-595x595.png 595w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-768x768.png 768w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-1536x1536.png 1536w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111-720x720.png 720w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/Photoroom-20250209_141111.png 2048w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#906b5d\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-white-color has-text-color has-background has-link-color has-large-font-size wp-elements-6e790c143711aaf0dbcae4f41e43a88d wp-block-paragraph\" style=\"background-color:#0000004a\">Willet &#8211; 7yo &#8211; 54%<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un Rye Whiskey, je pense que c&rsquo;est le premier sur ce piti blog, bienvenue donc \u00e0 Willet qui existe depuis 1937 dans le Kentucky. En 2012, 32 ans apr\u00e8s la fermeture de la distillerie originelle, la famille Willett-Kulsveen a relanc\u00e9 la Willett Distilling Company, et en 2025 elle fait son retour sur le march\u00e9 allemand avec cette s\u00e9lection.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nez<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Assez frais, sur le citron confits l\u00e9g\u00e8rement am\u00e8re, les fruits plus tropicaux, la vanille, le caramel sal\u00e9, des herbes comme la coriandre hach\u00e9es, les baies rouges, du pain grill\u00e9 beurr\u00e9, des fruits \u00e0 coque torr\u00e9fi\u00e9s et un c\u00f4t\u00e9 savon genre \u00ab\u00a0Port Mourant\u00a0\u00bb&#8230; comique tout \u00e7a dans le m\u00eame verre en fait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&rsquo;\u00e9tant pas trop habitu\u00e9 \u00e0 ce genre de profil, je ne sais pas si c&rsquo;est \u00e9tonnant ou pas, mais c&rsquo;est plut\u00f4t int\u00e9ressant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bouche<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La bouche est tout aussi parfum\u00e9e avec pas mal de fruits comme la past\u00e8que, la mangue, la p\u00eache melba, avec une belle rasade de vanille, de miel, de caramel beurre\/sal\u00e9, de p\u00e9tales de rose, de fruits \u00e0 coque comme les noisettes, de petits beurres et un bois\u00e9 marqu\u00e9 sans pour autant tout \u00e9craser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 le jeune \u00e2ge et l&rsquo;absence de r\u00e9duction, \u00e7a passe plut\u00f4t pas mal \ud83d\ude0b<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">243\u20ac<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9 bien, quelle histoire ce Willet 7 ans, je pense avoir pr\u00e9f\u00e9r\u00e9 ce qui se passe en bouche, mais c&rsquo;est clairement une tr\u00e8s belle s\u00e9lection !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Score<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">89\/100<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revoici les copains du Wu Dram Clan avec quelques nouveaut\u00e9s que je vous propose de d\u00e9couvrir rapidement. Au programme, deux rhums et un rye whiskey mis en bouteilles pour nos trois \u00e9picuriens d&rsquo;outre-Rhin. Et le moins que l&rsquo;on puisse dire est qu&rsquo;ils ne prennent pas trop le temps de se <a href=\"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/\" class=\"btn btn-link continue-link\">Voir plus&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":22929,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2908,4],"tags":[],"class_list":["post-22928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bourbon-rye-whiskey","category-rhum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Some Kind Ov Wu Dram Clan -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Some Kind Ov Wu Dram Clan -\" \/>\n<meta property=\"og:description\" content=\"Revoici les copains du Wu Dram Clan avec quelques nouveaut\u00e9s que je vous propose de d\u00e9couvrir rapidement. Au programme, deux rhums et un rye whiskey mis en bouteilles pour nos trois \u00e9picuriens d&rsquo;outre-Rhin. Et le moins que l&rsquo;on puisse dire est qu&rsquo;ils ne prennent pas trop le temps de se Voir plus...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leblogaroger\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/leblogaroger\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-09T14:37:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T17:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/\"},\"author\":{\"name\":\"Roger\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"headline\":\"Some Kind Ov Wu Dram Clan\",\"datePublished\":\"2025-02-09T14:37:21+00:00\",\"dateModified\":\"2025-02-10T17:25:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/\"},\"wordCount\":1017,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wudram.png\",\"articleSection\":[\"Bourbon\\\/Rye Whiskey\",\"Rhum\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/\",\"name\":\"Some Kind Ov Wu Dram Clan -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wudram.png\",\"datePublished\":\"2025-02-09T14:37:21+00:00\",\"dateModified\":\"2025-02-10T17:25:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wudram.png\",\"contentUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/wudram.png\",\"width\":1020,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2025\\\/02\\\/09\\\/some-kind-ov-wu-dram-clan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leblogaroger.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Some Kind Ov Wu Dram Clan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/\",\"name\":\"\",\"description\":\"Mundi placet et spiritus minima...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leblogaroger.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\",\"name\":\"Roger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"caption\":\"Roger\"},\"sameAs\":[\"http:\\\/\\\/www.leblogaroger.eu\",\"https:\\\/\\\/www.facebook.com\\\/leblogaroger\",\"https:\\\/\\\/www.instagram.com\\\/rogercaroni\\\/\"],\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/author\\\/admin5027\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Some Kind Ov Wu Dram Clan -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/","og_locale":"fr_FR","og_type":"article","og_title":"Some Kind Ov Wu Dram Clan -","og_description":"Revoici les copains du Wu Dram Clan avec quelques nouveaut\u00e9s que je vous propose de d\u00e9couvrir rapidement. Au programme, deux rhums et un rye whiskey mis en bouteilles pour nos trois \u00e9picuriens d&rsquo;outre-Rhin. Et le moins que l&rsquo;on puisse dire est qu&rsquo;ils ne prennent pas trop le temps de se Voir plus...","og_url":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/","article_publisher":"https:\/\/www.facebook.com\/leblogaroger\/","article_author":"https:\/\/www.facebook.com\/leblogaroger","article_published_time":"2025-02-09T14:37:21+00:00","article_modified_time":"2025-02-10T17:25:31+00:00","og_image":[{"width":1020,"height":600,"url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png","type":"image\/png"}],"author":"Roger","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Roger","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#article","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/"},"author":{"name":"Roger","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"headline":"Some Kind Ov Wu Dram Clan","datePublished":"2025-02-09T14:37:21+00:00","dateModified":"2025-02-10T17:25:31+00:00","mainEntityOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/"},"wordCount":1017,"commentCount":0,"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png","articleSection":["Bourbon\/Rye Whiskey","Rhum"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/","url":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/","name":"Some Kind Ov Wu Dram Clan -","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#primaryimage"},"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png","datePublished":"2025-02-09T14:37:21+00:00","dateModified":"2025-02-10T17:25:31+00:00","author":{"@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"breadcrumb":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#primaryimage","url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png","contentUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2025\/02\/wudram.png","width":1020,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/leblogaroger.eu\/index.php\/2025\/02\/09\/some-kind-ov-wu-dram-clan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leblogaroger.eu\/"},{"@type":"ListItem","position":2,"name":"Some Kind Ov Wu Dram Clan"}]},{"@type":"WebSite","@id":"https:\/\/leblogaroger.eu\/#website","url":"https:\/\/leblogaroger.eu\/","name":"","description":"Mundi placet et spiritus minima...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leblogaroger.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a","name":"Roger","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","caption":"Roger"},"sameAs":["http:\/\/www.leblogaroger.eu","https:\/\/www.facebook.com\/leblogaroger","https:\/\/www.instagram.com\/rogercaroni\/"],"url":"https:\/\/leblogaroger.eu\/index.php\/author\/admin5027\/"}]}},"_links":{"self":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/22928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/comments?post=22928"}],"version-history":[{"count":23,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/22928\/revisions"}],"predecessor-version":[{"id":22957,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/22928\/revisions\/22957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media\/22929"}],"wp:attachment":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media?parent=22928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/categories?post=22928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/tags?post=22928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}