{"id":17573,"date":"2023-05-20T15:22:41","date_gmt":"2023-05-20T13:22:41","guid":{"rendered":"https:\/\/leblogaroger.eu\/?p=17573"},"modified":"2023-05-20T16:07:30","modified_gmt":"2023-05-20T14:07:30","slug":"neisson-armada-drop-by-drop-jeroboam-3l","status":"publish","type":"post","link":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/","title":{"rendered":"Neisson Armada Drop by Drop J\u00e9roboam 3L"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Apr\u00e8s avoir f\u00eat\u00e9 ses 85 et 88 ans d&rsquo;existence, la c\u00e9l\u00e8bre distillerie Neisson en Martinique nous revient pour ses 90 ans cette ann\u00e9e&#8230; Y&rsquo;a rien \u00e0 faire, quand on a le sens de la f\u00eate, le moindre petit \u00e9v\u00e8nement est directement pr\u00e9texte \u00e0 festoyer ! Et moi j&rsquo;aime bien cette philosophie..c&rsquo;est m\u00eame un art de vivre je dirais !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et que nous r\u00e9servent-ils apr\u00e8s les Armada, les VSOP et autres vieux Bio ? Un nouveau Tatanka ? Un nouveau rhum blanc ou encore un nouveau mill\u00e9simes ? Que neni, ils reviennent simplement avec un J\u00e9roboam d&rsquo;un assemblage des plus vieux mill\u00e9simes se trouvant dans les chais de la distillerie&#8230;. oui, rien que \u00e7a !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors \u00e9videmment, vu de loin cela ne semble plus si festif que cela au final, mais au moins cela aura le m\u00e9rite de marquer le coup pour les 90 ans de la distillerie. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bon ok, ils nous ont aussi propos\u00e9 un \u00e9lev\u00e9 sous bois en f\u00fbt de <strong>Mizunara<\/strong>,<strong> <\/strong>mais ce dernier a disparu des radars aussi rapidement que &#8230; Heu, un truc tr\u00e8s rapide \ud83d\ude05<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ce qui est de ce Neisson \u201cDrop By drop\u201d, il s&rsquo;agit d&rsquo;un assemblage r\u00e9alis\u00e9 <strong>goutte \u00e0 goutte<\/strong> \u00e0 l\u2019aide d\u2019une pipette et compos\u00e9 de 90cl d\u2019Armada <strong>1997<\/strong>, 70cl du Sacha <strong>2003<\/strong>, 70cl d\u2019Armada <strong>1991 <\/strong>et de 70cl d\u2019Armada <strong>1992 <\/strong>pour 3 litres d&rsquo;un rhum 5 \u00e9toiles titrant 45.4% d&rsquo;alcool ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le tout dans une carafe de grand malade et limit\u00e9 \u00e0 seulement <strong>10 exemplaires<\/strong> pour la modique somme de <strong>27.500 \u20ac<\/strong>&#8230;. oui, ici le concept d&rsquo;une pour boire et l&rsquo;autre pour la collection tombe un peu \u00e0 l&rsquo;eau.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h52_43.png\"><img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"335\" data-id=\"17591\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h52_43.png\" alt=\"\" class=\"wp-image-17591\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h52_43.png 340w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h52_43-61x60.png 61w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"841\" height=\"1200\" data-id=\"17592\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2.jpg\" alt=\"\" class=\"wp-image-17592\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2.jpg 841w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2-595x849.jpg 595w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2-768x1096.jpg 768w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/rhum-agricole-neisson-armada-drop-by-drop-jeroboam-3l-2-42x60.jpg 42w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h55_51.png\"><img loading=\"lazy\" decoding=\"async\" width=\"486\" height=\"174\" data-id=\"17593\" src=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h55_51.png\" alt=\"\" class=\"wp-image-17593\" srcset=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h55_51.png 486w, https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/2023-05-20_12h55_51-168x60.png 168w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Je vous propose l&rsquo;explication donn\u00e9e par Alex Bobbi \u00e0 <a href=\"https:\/\/rumporter.com\/neisson-voit-grand-pour-ses-90-ans\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rumporter <\/a>, ce sera plus rapide !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Au d\u00e9but, j\u2019ai voulu m\u2019inspirer de cette fa\u00e7on de d\u00e9guster les whiskies avec la goutte d\u2019eau qui cr\u00e9e le choc thermique \u00e0 la surface et fait ressortir les ar\u00f4mes.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En faisant tomber goutte \u00e0 goutte le rhum le plus bas en degr\u00e9 (donc plus charg\u00e9 en eau) dans un rhum d\u2019un degr\u00e9 plus \u00e9lev\u00e9 on pouvait cr\u00e9er ce choc thermique. En mettant un thermom\u00e8tre dans le m\u00e9lange je ne gagnais que 1 \u00e0 deux degr\u00e9s d\u2019augmentation de temp\u00e9rature car les rhums de l\u2019assemblage \u00e0 savoir (90 cl d\u2019Armada 1997, 70 cl d\u2019Armada 1991, 70 cl d\u2019armada 1992 et 70 cl de Sacha 2003) ont des degr\u00e9s proches contrairement au m\u00e9lange eau alcool qui reste une r\u00e9action exothermique.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Par contre, on pouvait observer un ph\u00e9nom\u00e8ne extraordinaire avec les gouttes d\u2019alcool qui glissaient \u00e0 la surface du m\u00e9lange comme si on se retrouvait avec des huiles essentielles ce qui embaumait la salle.<\/em>\u00ab\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grand merci \u00e0 mon QDD \u00ab\u00a05 \u00e9toiles\u00a0\u00bb d&rsquo;avoir rendu possible cette remarquable d\u00e9gustation !<\/p>\n\n\n\n<div class=\"wp-block-cover is-repeated\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div role=\"img\" class=\"wp-block-cover__image-background wp-image-17582 is-repeated\" style=\"background-position:50% 50%;background-image:url(https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/neisson-logo-1.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Nez<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s chaleureux et expressif, on retrouve un rhum tr\u00e8s g\u00e9n\u00e9reux et gourmand, ultra typ\u00e9 Neisson. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bois\u00e9 est fin et \u00e9l\u00e9gant, les agrumes avec l&rsquo;orange sanguine en t\u00eate se lient parfaitement aux fruits secs tels la noisette, le tout napp\u00e9 par un beau chocolat noir au caramel sal\u00e9\/poivr\u00e9&#8230; Le profil est tr\u00e8s patin\u00e9, mieleux et beurr\u00e9, c&rsquo;est ultra charmeur !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La partie plus sombre de ce rhum nous apporte pas mal de vanille, de tabac, de chocolat au lait, de cuir et une pointe de r\u00e9glisse mais le fruit\u00e9 n&rsquo;est jamais loin, sous forme de citron vert, orange voir m\u00eame des fruits plus exotiques tels la banane, la mangue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bref, un beau p\u00e9riple au travers de 4 grands mill\u00e9simes de la c\u00e9l\u00e8bre distillerie ! Un nez incroyable de concentration, de gourmandise et d&rsquo;\u00e9quilibre !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comptez une bonne petite demi heure afin que tout ce concentr\u00e9 d&rsquo;ar\u00f4mes puisse se pr\u00e9senter correctement \u00e0 vous&#8230; D\u00e9guster ce genre de monument \u00e0 la va vite serait dommage !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bouche<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La bouche est bien entendu dans la m\u00eame \u00e9l\u00e9gance, proposant une exp\u00e9rience terriblement Neisson, au bois\u00e9 pr\u00e9sent mais tr\u00e8s gourmand et toujours accompagn\u00e9 d&rsquo;un fin caramel et de quelques fruits bien juteux qui viennent ajouter une belle fraicheur \u00e0 l&rsquo;ensemble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Directement, les fruits secs, la vanille bien grasse, le nougat, la r\u00e9glisse, le bois\u00e9 toast\u00e9 et torrefi\u00e9, qui d\u00e9gage une tr\u00e8s belle pointe de poudre de cacao, prennent une belle place dans ce spiritueux d&rsquo;exception.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les agrumes et autres fruits tropicaux sont eux l\u00e9g\u00e8rement en retrait par rapport au nez, mais apportent quand m\u00eame leur pierre \u00e0 l&rsquo;\u00e9difice avec une belle fraicheur et une l\u00e9g\u00e8re acidit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La finale est superbement toast\u00e9e et \u00e9pic\u00e9e sans dutout \u00eatre oppressante, juste \u00e9l\u00e9gante et infinie&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Superbe travail, tr\u00e8s belle r\u00e9alisation ! Un tout grand rhum agricole de la Martinique.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Prix<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">27.500 \u20ac (<em>hooo \u00e7a va, gueulez pas, y&rsquo;a 3 litres hein !<\/em>)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusion<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00e0 o\u00f9 certains nous proposent des formats 10\/20\/50 cl afin de pouvoir en faire profiter le maximum de monde, Neisson prend tout le monde de revers et d\u00e9barque donc avec une carafe de 3 litres !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J&rsquo;avoue ne pas trop comprendre l&rsquo;int\u00e9r\u00eat direct de la chose, imaginons un instant qu&rsquo;un des 10 acheteurs de cette carafe l&rsquo;ouvre, je ne vous dit pas l&rsquo;\u00e9tat du rhum une fois la carafe vide de la moiti\u00e9 de son contenu&#8230; bonjour l&rsquo;oxydation sur une rhum assez \u00e9l\u00e9gant !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais bon, j&rsquo;imagine que ces gars l\u00e0 auront une carafe vide d&rsquo;un armada &rsquo;91, donc le probl\u00e8me n&rsquo;est pas vraiment l\u00e0 \ud83d\ude42<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais hormis cette l\u00e9g\u00e8re consid\u00e9ration sur le marketing de ce J\u00e9roboam, ce rhum est juste<strong> incroyablement bon<\/strong>&#8230; Un vrai travail d&rsquo;orf\u00e8vre, tant l&rsquo;\u00e9quilibre de cet assemblage est impressionnant. Il y a tout l\u00e0 dedans, mais de mani\u00e8re tr\u00e8s fine et \u00e9l\u00e9gante et avec une int\u00e9gration de l&rsquo;alcool proche de la prefection. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du grand art !<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Score<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">95\/100<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir f\u00eat\u00e9 ses 85 et 88 ans d&rsquo;existence, la c\u00e9l\u00e8bre distillerie Neisson en Martinique nous revient pour ses 90 ans cette ann\u00e9e&#8230; Y&rsquo;a rien \u00e0 faire, quand on a le sens de la f\u00eate, le moindre petit \u00e9v\u00e8nement est directement pr\u00e9texte \u00e0 festoyer ! Et moi j&rsquo;aime bien cette <a href=\"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/\" class=\"btn btn-link continue-link\">Voir plus&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":17574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9,122,19,16],"class_list":["post-17573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rhum","tag-bois","tag-fruits","tag-martinique","tag-rhum-agricole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neisson Armada Drop by Drop J\u00e9roboam 3L -<\/title>\n<meta name=\"description\" content=\"D\u00e9gustation d&#039;exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&amp;1992... Le tout en format J\u00e9roboam !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neisson Armada Drop by Drop J\u00e9roboam 3L -\" \/>\n<meta property=\"og:description\" content=\"D\u00e9gustation d&#039;exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&amp;1992... Le tout en format J\u00e9roboam !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leblogaroger\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/leblogaroger\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-20T13:22:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-20T14:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/\"},\"author\":{\"name\":\"Roger\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"headline\":\"Neisson Armada Drop by Drop J\u00e9roboam 3L\",\"datePublished\":\"2023-05-20T13:22:41+00:00\",\"dateModified\":\"2023-05-20T14:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/\"},\"wordCount\":999,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/dropbyDrop.png\",\"keywords\":[\"bois\",\"fruits\",\"Martinique\",\"rhum agricole\"],\"articleSection\":[\"Rhum\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/\",\"name\":\"Neisson Armada Drop by Drop J\u00e9roboam 3L -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/dropbyDrop.png\",\"datePublished\":\"2023-05-20T13:22:41+00:00\",\"dateModified\":\"2023-05-20T14:07:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\"},\"description\":\"D\u00e9gustation d'exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&1992... Le tout en format J\u00e9roboam !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/dropbyDrop.png\",\"contentUrl\":\"https:\\\/\\\/leblogaroger.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/dropbyDrop.png\",\"width\":1020,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/2023\\\/05\\\/20\\\/neisson-armada-drop-by-drop-jeroboam-3l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leblogaroger.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neisson Armada Drop by Drop J\u00e9roboam 3L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#website\",\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/\",\"name\":\"\",\"description\":\"Mundi placet et spiritus minima...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leblogaroger.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leblogaroger.eu\\\/#\\\/schema\\\/person\\\/bc869e7715118449352dfd48d4d8e59a\",\"name\":\"Roger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g\",\"caption\":\"Roger\"},\"sameAs\":[\"http:\\\/\\\/www.leblogaroger.eu\",\"https:\\\/\\\/www.facebook.com\\\/leblogaroger\",\"https:\\\/\\\/www.instagram.com\\\/rogercaroni\\\/\"],\"url\":\"https:\\\/\\\/leblogaroger.eu\\\/index.php\\\/author\\\/admin5027\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neisson Armada Drop by Drop J\u00e9roboam 3L -","description":"D\u00e9gustation d'exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&1992... Le tout en format J\u00e9roboam !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/","og_locale":"fr_FR","og_type":"article","og_title":"Neisson Armada Drop by Drop J\u00e9roboam 3L -","og_description":"D\u00e9gustation d'exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&1992... Le tout en format J\u00e9roboam !","og_url":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/","article_publisher":"https:\/\/www.facebook.com\/leblogaroger\/","article_author":"https:\/\/www.facebook.com\/leblogaroger","article_published_time":"2023-05-20T13:22:41+00:00","article_modified_time":"2023-05-20T14:07:30+00:00","og_image":[{"width":1020,"height":600,"url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png","type":"image\/png"}],"author":"Roger","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Roger","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#article","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/"},"author":{"name":"Roger","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"headline":"Neisson Armada Drop by Drop J\u00e9roboam 3L","datePublished":"2023-05-20T13:22:41+00:00","dateModified":"2023-05-20T14:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/"},"wordCount":999,"commentCount":0,"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png","keywords":["bois","fruits","Martinique","rhum agricole"],"articleSection":["Rhum"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/","url":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/","name":"Neisson Armada Drop by Drop J\u00e9roboam 3L -","isPartOf":{"@id":"https:\/\/leblogaroger.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#primaryimage"},"image":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#primaryimage"},"thumbnailUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png","datePublished":"2023-05-20T13:22:41+00:00","dateModified":"2023-05-20T14:07:30+00:00","author":{"@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a"},"description":"D\u00e9gustation d'exception avec ce Neisson Drop By Drop issu des mill\u00e9sime 1997-2003-1991&1992... Le tout en format J\u00e9roboam !","breadcrumb":{"@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#primaryimage","url":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png","contentUrl":"https:\/\/leblogaroger.eu\/wp-content\/uploads\/2023\/05\/dropbyDrop.png","width":1020,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/leblogaroger.eu\/index.php\/2023\/05\/20\/neisson-armada-drop-by-drop-jeroboam-3l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leblogaroger.eu\/"},{"@type":"ListItem","position":2,"name":"Neisson Armada Drop by Drop J\u00e9roboam 3L"}]},{"@type":"WebSite","@id":"https:\/\/leblogaroger.eu\/#website","url":"https:\/\/leblogaroger.eu\/","name":"","description":"Mundi placet et spiritus minima...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leblogaroger.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/leblogaroger.eu\/#\/schema\/person\/bc869e7715118449352dfd48d4d8e59a","name":"Roger","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8ea28e5fd25988ff8bc342a98fc2a2e1b597fa211dd6c4071e7699eaef56ddb?s=96&d=mm&r=g","caption":"Roger"},"sameAs":["http:\/\/www.leblogaroger.eu","https:\/\/www.facebook.com\/leblogaroger","https:\/\/www.instagram.com\/rogercaroni\/"],"url":"https:\/\/leblogaroger.eu\/index.php\/author\/admin5027\/"}]}},"_links":{"self":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/17573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/comments?post=17573"}],"version-history":[{"count":55,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/17573\/revisions"}],"predecessor-version":[{"id":17638,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/posts\/17573\/revisions\/17638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media\/17574"}],"wp:attachment":[{"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/media?parent=17573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/categories?post=17573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leblogaroger.eu\/index.php\/wp-json\/wp\/v2\/tags?post=17573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}